{"id":5146,"date":"2015-01-23T12:28:06","date_gmt":"2015-01-23T11:28:06","guid":{"rendered":"http:\/\/www.lacuisinedejosy.com\/?p=5146"},"modified":"2016-01-23T08:21:57","modified_gmt":"2016-01-23T07:21:57","slug":"carottes-confites-sans-casserole-et-sans-eau-comme-pierre-desproges","status":"publish","type":"post","link":"https:\/\/www.lacuisinedejosy.com\/index.php\/carottes-confites-sans-casserole-et-sans-eau-comme-pierre-desproges\/","title":{"rendered":"Carottes confites (sans casserole et sans eau, comme Pierre Desproges)"},"content":{"rendered":"<p><em>\u00ab\u00a0Si vous voulez faire cuire des carottes sans casserole et sans eau, c&rsquo;est tr\u00e8s simple.\u00a0<\/em><em>Vous prenez 9 carottes, c&rsquo;est tr\u00e8s important, vous prenez vos 9 carottes, vous les comptez bien soigneusement, les carottes sont 9.\u00a0<\/em><em>Vous jetez une des 9 carottes, les carottes sont qu&rsquo;huit.\u00a0\u00bb Pierre Desproges<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pr\u00e9chauffer le four \u00e0 190\u00b0C<\/strong><\/p>\n<p>Pr\u00e9parer\u00a0les carottes, les tailler en b\u00e2tonnets ou en rondelles un peu \u00e9paisses.<\/p>\n<p>Eplucher et ciseler finement les \u00e9chalotes, presser la gousse d&rsquo;ail.<\/p>\n<p>Dans un bol, mettre l&rsquo;huile d&rsquo;olive, le miel, le cumin, les \u00e9chalotes et l&rsquo;ail, saler et poivrer.<\/p>\n<p>R\u00e9partir les carottes dans un plat allant au four, verser le contenu du bol dessus, bien m\u00e9langer.<\/p>\n<p>Faire cuire 30 \u00e0 40 mn au four \u00e0 190\u00b0C. Remuer de temps en temps au cours de la cuisson. Server chaud ou froid.<\/p>\n<p>&nbsp;<\/p>\n<p>Il est possible de ne pas utiliser le four et de faire cuire les carottes \u00e0 la vapeur, les mettre ensuite dans un saladier et verser l&rsquo;assaisonnement, bien m\u00e9langer.<\/p>\n<p><a href=\"http:\/\/www.lacuisinedejosy.com\/wp-content\/uploads\/2015\/01\/Carottes-confites.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-5148\" src=\"http:\/\/www.lacuisinedejosy.com\/wp-content\/uploads\/2015\/01\/Carottes-confites.jpg\" alt=\"Carottes confites\" width=\"640\" height=\"640\" srcset=\"https:\/\/www.lacuisinedejosy.com\/wp-content\/uploads\/2015\/01\/Carottes-confites.jpg 640w, https:\/\/www.lacuisinedejosy.com\/wp-content\/uploads\/2015\/01\/Carottes-confites-150x150.jpg 150w, https:\/\/www.lacuisinedejosy.com\/wp-content\/uploads\/2015\/01\/Carottes-confites-300x300.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Si vous voulez faire cuire des carottes sans casserole et sans eau, c&rsquo;est tr\u00e8s simple.\u00a0Vous prenez 9 carottes, c&rsquo;est tr\u00e8s important, vous prenez vos 9 carottes, vous les&#8230; <a href=\"https:\/\/www.lacuisinedejosy.com\/index.php\/carottes-confites-sans-casserole-et-sans-eau-comme-pierre-desproges\/\">Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[144,34,145,141],"class_list":["post-5146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accompagnements","tag-ail","tag-carotte","tag-cumin","tag-echalote"],"_links":{"self":[{"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/posts\/5146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/comments?post=5146"}],"version-history":[{"count":3,"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/posts\/5146\/revisions"}],"predecessor-version":[{"id":5150,"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/posts\/5146\/revisions\/5150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/media\/5147"}],"wp:attachment":[{"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/media?parent=5146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/categories?post=5146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacuisinedejosy.com\/index.php\/wp-json\/wp\/v2\/tags?post=5146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}